{"id":15589,"date":"2026-03-26T17:13:20","date_gmt":"2026-03-26T16:13:20","guid":{"rendered":"https:\/\/www.complicesdeloire.com\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/"},"modified":"2026-03-26T17:30:22","modified_gmt":"2026-03-26T16:30:22","slug":"touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide","status":"publish","type":"post","link":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/","title":{"rendered":"TOURAINE SAUVIGNON &#8220;POINTE D&#8217;AGRUMES&#8221;: GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE"},"content":{"rendered":"\n<figure class=\"wp-block-image alignleft size-full is-resized\"><a href=\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1071\" height=\"765\" src=\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png\" alt=\"\" class=\"wp-image-15585\" style=\"aspect-ratio:1.7786724822457083;width:534px;height:auto\" srcset=\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png 1071w, https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4-300x214.png 300w, https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4-1024x731.png 1024w, https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4-768x549.png 768w\" sizes=\"(max-width: 1071px) 100vw, 1071px\" \/><\/a><\/figure>\n\n<p class=\"wp-block-paragraph\">Another fine accolade for Complices de Loire: our Touraine Sauvignon &#8220;Pointe d&#8217;Agrumes&#8221; has been awarded the <a href=\"https:\/\/vigneron.gilbertgaillard.com\/fr\">Gilbert &amp; Gaillard<\/a> Gold Medal.<\/p>\n\n<p class=\"wp-block-paragraph\">This Sauvignon seduces with its bright, lively profile, marked by bright citrus notes and thirst-quenching freshness. A precise, expressive and accessible cuv\u00e9e, ideal for lovers of fresh, aromatic white wines. <\/p>\n\n<p class=\"wp-block-paragraph\">This cuv\u00e9e is available in Quebec through the <a href=\"https:\/\/www.saq.com\/fr\/12260002\">SAQ<\/a> network (SAQ code: 12260002). A great opportunity to discover \u2013 or rediscover \u2013 this Touraine Sauvignon by Complices de Loire.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Another fine accolade for Complices de Loire: our Touraine Sauvignon &#8220;Pointe d&#8217;Agrumes&#8221; has been awarded the Gilbert &amp; Gaillard Gold Medal. This Sauvignon seduces with its bright, lively profile, marked by bright citrus notes and thirst-quenching freshness. A precise, expressive and accessible cuv\u00e9e, ideal for lovers of fresh, aromatic white wines. This cuv\u00e9e is available [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-15589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salon-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TOURAINE SAUVIGNON &quot;POINTE D&#039;AGRUMES&quot;: GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE - Complices de Loire<\/title>\n<meta name=\"description\" content=\"Complices de Loire&#039;s Touraine Sauvignon &quot;Pointe d&#039;Agrumes&quot; wins Gilbert &amp; Gaillard Gold Medal. Available at the SAQ (Quebec), discover a fresh, luminous Sauvignon.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TOURAINE SAUVIGNON &quot;POINTE D&#039;AGRUMES&quot;: GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE - Complices de Loire\" \/>\n<meta property=\"og:description\" content=\"Complices de Loire&#039;s Touraine Sauvignon &quot;Pointe d&#039;Agrumes&quot; wins Gilbert &amp; Gaillard Gold Medal. Available at the SAQ (Quebec), discover a fresh, luminous Sauvignon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/\" \/>\n<meta property=\"og:site_name\" content=\"Complices de Loire\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T16:13:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T16:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1071\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yuli@\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yuli@\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/\",\"url\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/\",\"name\":\"TOURAINE SAUVIGNON \\\"POINTE D'AGRUMES\\\": GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE - Complices de Loire\",\"isPartOf\":{\"@id\":\"https:\/\/www.complicesdeloire.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png\",\"datePublished\":\"2026-03-26T16:13:20+00:00\",\"dateModified\":\"2026-03-26T16:30:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.complicesdeloire.com\/#\/schema\/person\/3627e800906e82041f542fbfd91638d7\"},\"description\":\"Complices de Loire's Touraine Sauvignon \\\"Pointe d'Agrumes\\\" wins Gilbert & Gaillard Gold Medal. Available at the SAQ (Quebec), discover a fresh, luminous Sauvignon.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#primaryimage\",\"url\":\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png\",\"contentUrl\":\"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png\",\"width\":1071,\"height\":765},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.complicesdeloire.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TOURAINE SAUVIGNON &#8220;POINTE D&#8217;AGRUMES&#8221;: GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.complicesdeloire.com\/#website\",\"url\":\"https:\/\/www.complicesdeloire.com\/\",\"name\":\"Complices de Loire\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.complicesdeloire.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.complicesdeloire.com\/#\/schema\/person\/3627e800906e82041f542fbfd91638d7\",\"name\":\"Yuli@\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.complicesdeloire.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3fdfdf4339bf743d7494d6a3148fc995b62b6c3f8a1f31c688b1e1d3bae072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3fdfdf4339bf743d7494d6a3148fc995b62b6c3f8a1f31c688b1e1d3bae072c?s=96&d=mm&r=g\",\"caption\":\"Yuli@\"},\"url\":\"https:\/\/www.complicesdeloire.com\/en\/author\/yuli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TOURAINE SAUVIGNON \"POINTE D'AGRUMES\": GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE - Complices de Loire","description":"Complices de Loire's Touraine Sauvignon \"Pointe d'Agrumes\" wins Gilbert & Gaillard Gold Medal. Available at the SAQ (Quebec), discover a fresh, luminous Sauvignon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/","og_locale":"en_US","og_type":"article","og_title":"TOURAINE SAUVIGNON \"POINTE D'AGRUMES\": GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE - Complices de Loire","og_description":"Complices de Loire's Touraine Sauvignon \"Pointe d'Agrumes\" wins Gilbert & Gaillard Gold Medal. Available at the SAQ (Quebec), discover a fresh, luminous Sauvignon.","og_url":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/","og_site_name":"Complices de Loire","article_published_time":"2026-03-26T16:13:20+00:00","article_modified_time":"2026-03-26T16:30:22+00:00","og_image":[{"width":1071,"height":765,"url":"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png","type":"image\/png"}],"author":"Yuli@","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Yuli@"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/","url":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/","name":"TOURAINE SAUVIGNON \"POINTE D'AGRUMES\": GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE - Complices de Loire","isPartOf":{"@id":"https:\/\/www.complicesdeloire.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#primaryimage"},"image":{"@id":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png","datePublished":"2026-03-26T16:13:20+00:00","dateModified":"2026-03-26T16:30:22+00:00","author":{"@id":"https:\/\/www.complicesdeloire.com\/#\/schema\/person\/3627e800906e82041f542fbfd91638d7"},"description":"Complices de Loire's Touraine Sauvignon \"Pointe d'Agrumes\" wins Gilbert & Gaillard Gold Medal. Available at the SAQ (Quebec), discover a fresh, luminous Sauvignon.","breadcrumb":{"@id":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#primaryimage","url":"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png","contentUrl":"https:\/\/www.complicesdeloire.com\/wp-content\/uploads\/2026\/03\/Actualites-Site-WebLinkedIn-4.png","width":1071,"height":765},{"@type":"BreadcrumbList","@id":"https:\/\/www.complicesdeloire.com\/en\/touraine-sauvignon-pointe-dagrumes-gold-medal-in-the-gilbert-gaillard-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.complicesdeloire.com\/"},{"@type":"ListItem","position":2,"name":"TOURAINE SAUVIGNON &#8220;POINTE D&#8217;AGRUMES&#8221;: GOLD MEDAL IN THE GILBERT &amp; GAILLARD GUIDE"}]},{"@type":"WebSite","@id":"https:\/\/www.complicesdeloire.com\/#website","url":"https:\/\/www.complicesdeloire.com\/","name":"Complices de Loire","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.complicesdeloire.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.complicesdeloire.com\/#\/schema\/person\/3627e800906e82041f542fbfd91638d7","name":"Yuli@","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.complicesdeloire.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3fdfdf4339bf743d7494d6a3148fc995b62b6c3f8a1f31c688b1e1d3bae072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3fdfdf4339bf743d7494d6a3148fc995b62b6c3f8a1f31c688b1e1d3bae072c?s=96&d=mm&r=g","caption":"Yuli@"},"url":"https:\/\/www.complicesdeloire.com\/en\/author\/yuli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/posts\/15589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/comments?post=15589"}],"version-history":[{"count":4,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/posts\/15589\/revisions"}],"predecessor-version":[{"id":15594,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/posts\/15589\/revisions\/15594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/media\/15586"}],"wp:attachment":[{"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/media?parent=15589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/categories?post=15589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.complicesdeloire.com\/en\/wp-json\/wp\/v2\/tags?post=15589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}